{"id":3861,"date":"2025-08-30T00:08:06","date_gmt":"2025-08-29T22:08:06","guid":{"rendered":"https:\/\/groovit-dancestudio.com\/?page_id=3861"},"modified":"2026-02-18T22:36:03","modified_gmt":"2026-02-18T21:36:03","slug":"nos-soirees","status":"publish","type":"page","link":"https:\/\/groovit-dancestudio.com\/index.php\/nos-soirees\/","title":{"rendered":"Nos soir\u00e9es &amp; pratiques"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3861\" class=\"elementor elementor-3861\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bbec6f4 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"bbec6f4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-635691c\" data-id=\"635691c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-26bc73b3 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"26bc73b3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-62882c33\" data-id=\"62882c33\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-247bf30d elementor-widget elementor-widget-text-editor\" data-id=\"247bf30d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 data-start=\"172\" data-end=\"222\">Nos Soir\u00e9es Blues et Swing \u00e0 Montreuil et Paris<\/h2><p data-start=\"224\" data-end=\"582\">Venez partager des moments inoubliables lors de nos <strong data-start=\"276\" data-end=\"298\">soir\u00e9es mensuelles<\/strong>, <strong data-start=\"300\" data-end=\"327\">soir\u00e9es exceptionnelles<\/strong> et <strong data-start=\"331\" data-end=\"352\">soir\u00e9es estivales<\/strong> organis\u00e9es \u00e0 Montreuil et \u00e0 Paris. Que vous soyez danseur d\u00e9butant ou confirm\u00e9, nos \u00e9v\u00e9nements sont pens\u00e9s pour vous faire d\u00e9couvrir et profiter pleinement de la danse blues et swing dans une ambiance conviviale et chaleureuse.<\/p><p data-start=\"584\" data-end=\"964\">Chaque soir\u00e9e commence par une <strong data-start=\"615\" data-end=\"629\">initiation<\/strong>, accessible \u00e0 tous, pour vous permettre de vous familiariser avec les pas et mouvements essentiels avant de vous lancer sur la piste. Ensuite, laissez-vous emporter par la musique ! La <strong data-start=\"815\" data-end=\"868\">majorit\u00e9 de nos soir\u00e9es propose des concerts live<\/strong>, avec des groupes de 1 \u00e0 6 musiciens, pour une exp\u00e9rience musicale authentique et envo\u00fbtante.<\/p><p data-start=\"966\" data-end=\"1222\">Nos soir\u00e9es sont principalement d\u00e9di\u00e9es au <strong data-start=\"1009\" data-end=\"1018\">blues<\/strong>, mais il nous arrive \u00e9galement d\u2019organiser des \u00e9v\u00e9nements <strong data-start=\"1077\" data-end=\"1102\">mixtes blues et swing<\/strong>, et tr\u00e8s exceptionnellement des <strong data-start=\"1135\" data-end=\"1166\">soir\u00e9es exclusivement swing<\/strong>, pour varier les plaisirs et surprendre nos danseurs.<\/p><p data-start=\"1224\" data-end=\"1521\">Au-del\u00e0 de la danse et de la musique, nos soir\u00e9es sont avant tout un lieu de <strong data-start=\"1301\" data-end=\"1329\">rencontres et de partage<\/strong>. Elles permettent de d\u00e9velopper la communaut\u00e9, de faire d\u00e9couvrir la richesse des danses blues et swing au plus grand nombre, et surtout de passer des moments conviviaux et joyeux ensemble.<\/p><p data-start=\"1523\" data-end=\"1683\">Rejoignez-nous \u00e0 Montreuil ou \u00e0 Paris pour danser, \u00e9couter de la bonne musique et vivre des soir\u00e9es uniques o\u00f9 la passion et la convivialit\u00e9 sont \u00e0 l\u2019honneur.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-33a8de99 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"33a8de99\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-62b77d5d\" data-id=\"62b77d5d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2def6eba elementor-widget-divider--view-line_text elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"2def6eba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<h2 class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\t\u00c0 VENIR\t\t\t\t<\/h2>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c760c0d elementor-widget elementor-widget-bridge_masonry_blog\" data-id=\"4c760c0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_masonry_blog.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class='q_masonry_blog'><div class=\"q_masonry_blog_grid_sizer\"><\/div><div class=\"q_masonry_blog_grid_gutter\"><\/div><article  class='post-3782 post type-post status-publish format-standard has-post-thumbnail hentry category-soiree '><div class=\"q_masonry_blog_post_image\"><a itemprop=\"url\" href=\"https:\/\/groovit-dancestudio.com\/index.php\/2025\/08\/30\/bal-envoute-mojo\/\" target=\"_self\"><img decoding=\"async\" itemprop=\"image\" src=\"https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2025\/02\/472769041_122169784418265131_5010776087486551817_n.jpg\" \/><\/a><\/div><div class=\"q_masonry_blog_post_text\"><h2 itemprop=\"name\" class=\"q_masonry_blog_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/groovit-dancestudio.com\/index.php\/2025\/08\/30\/bal-envoute-mojo\/\">BAL ENVO\u00dbT\u00c9 DES MOJO &#8211; initiation &#038; bal<\/a><\/h2><p itemprop=\"description\" class=\"q_masonry_blog_excerpt\">PROGRAMME Le groupe de blues MOJO entre en r\u00e9sidence au Chantier...<\/p><div class=\"q_masonry_blog_post_info\"><\/div><\/div><\/article><article  class='post-4319 post type-post status-publish format-standard has-post-thumbnail hentry category-soiree '><div class=\"q_masonry_blog_post_image\"><a itemprop=\"url\" href=\"https:\/\/groovit-dancestudio.com\/index.php\/2026\/02\/18\/pratique-blues-hebdomadaire\/\" target=\"_self\"><img decoding=\"async\" itemprop=\"image\" src=\"https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2025\/10\/16-e1766077804559.png\" \/><\/a><\/div><div class=\"q_masonry_blog_post_text\"><h2 itemprop=\"name\" class=\"q_masonry_blog_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/groovit-dancestudio.com\/index.php\/2026\/02\/18\/pratique-blues-hebdomadaire\/\">Pratique blues hebdomadaire<\/a><\/h2><p itemprop=\"description\" class=\"q_masonry_blog_excerpt\">PROGRAMME Les&nbsp;pratiques hebdomadaires, c\u2019est un moment pou...<\/p><div class=\"q_masonry_blog_post_info\"><\/div><\/div><\/article><article  class='post-3766 post type-post status-publish format-standard has-post-thumbnail hentry category-bal-blues category-evenements category-soiree '><div class=\"q_masonry_blog_post_image\"><a itemprop=\"url\" href=\"https:\/\/groovit-dancestudio.com\/index.php\/2026\/04\/17\/summer-blues-initiation-soiree-blues\/\" target=\"_self\"><img decoding=\"async\" itemprop=\"image\" src=\"https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2025\/08\/summer-blues_cover-FB.png\" \/><\/a><\/div><div class=\"q_masonry_blog_post_text\"><h2 itemprop=\"name\" class=\"q_masonry_blog_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/groovit-dancestudio.com\/index.php\/2026\/04\/17\/summer-blues-initiation-soiree-blues\/\">SUMMER BLUES : initiation &amp; Dj set<\/a><\/h2><p itemprop=\"description\" class=\"q_masonry_blog_excerpt\">PROGRAMME Viens apprendre les bases de la danse blues et danser g...<\/p><div class=\"q_masonry_blog_post_info\"><\/div><\/div><\/article><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b40229b elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"b40229b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-058832d\" data-id=\"058832d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac8a083 elementor-widget-divider--view-line_text elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"ac8a083\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<h2 class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\tPRATIQUES\t\t\t\t<\/h2>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55cdd38 elementor-widget elementor-widget-text-editor\" data-id=\"55cdd38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 data-start=\"172\" data-end=\"222\">Nos pratiques blues hebdomadaires<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f501ce elementor-widget elementor-widget-text-editor\" data-id=\"6f501ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><em>Les pratiques ont lieu chaque <b>lundi <\/b>au studio, de 19h30 \u00e0 22h15 et sont ouvertes \u00e0 tous les niveaux.<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f694e36 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"f694e36\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-cc08899\" data-id=\"cc08899\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-025bb8f elementor-widget elementor-widget-image\" data-id=\"025bb8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"546\" src=\"https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2025\/10\/16-e1766077804559-1024x546.png\" class=\"attachment-large size-large wp-image-4097\" alt=\"pratique danse blues montreuil\" srcset=\"https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2025\/10\/16-e1766077804559-1024x546.png 1024w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2025\/10\/16-e1766077804559-300x160.png 300w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2025\/10\/16-e1766077804559-768x410.png 768w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2025\/10\/16-e1766077804559-1536x819.png 1536w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2025\/10\/16-e1766077804559-700x373.png 700w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2025\/10\/16-e1766077804559.png 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7e72ee8\" data-id=\"7e72ee8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c13785c elementor-widget elementor-widget-text-editor\" data-id=\"c13785c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"242\" data-end=\"567\">Les <strong data-start=\"246\" data-end=\"273\">pratiques hebdomadaires<\/strong>, c\u2019est un moment pour danser, s\u2019entra\u00eener, r\u00e9viser ou simplement passer un bon moment autour de la <strong data-start=\"373\" data-end=\"388\">danse blues<\/strong>.<br data-start=\"389\" data-end=\"392\" \/>C\u2019est un espace libre, entre le <strong data-start=\"424\" data-end=\"433\">cours<\/strong> et le <strong data-start=\"440\" data-end=\"447\">bal<\/strong>, o\u00f9 chacun peut venir \u00e0 son rythme : pour revoir un cours, explorer une sensation, ou juste profiter de la musique.<\/p><p data-start=\"569\" data-end=\"831\">Tu peux venir seul\u00b7e ou avec un\u00b7e partenaire si tu veux travailler quelque chose de pr\u00e9cis.<br data-start=\"701\" data-end=\"704\" \/>C\u2019est aussi l\u2019occasion d\u2019\u00e9changer, de tester, de gagner en aisance et de continuer \u00e0 faire vivre la <strong data-start=\"804\" data-end=\"819\">danse blues<\/strong> ensemble<\/p><p data-start=\"569\" data-end=\"831\">\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-54b39469 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"54b39469\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a705c79\" data-id=\"a705c79\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1cf716 elementor-widget-divider--view-line_text elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"1cf716\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<h2 class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\tSOIR\u00c9ES PASS\u00c9S\t\t\t\t<\/h2>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-64ba035e elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"64ba035e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-3a5ecce3\" data-id=\"3a5ecce3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1dde6f93 elementor-widget elementor-widget-image\" data-id=\"1dde6f93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/fb.me\/e\/2v6n5IfiZ\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"531\" src=\"https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2020\/07\/Capture-d\u2019e\u0301cran-2020-07-04-a\u0300-16.37.33-e1756505728877-1024x531.png\" class=\"attachment-large size-large wp-image-521\" alt=\"soir\u00e9e blues paris\" srcset=\"https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2020\/07\/Capture-d\u2019e\u0301cran-2020-07-04-a\u0300-16.37.33-e1756505728877-1024x531.png 1024w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2020\/07\/Capture-d\u2019e\u0301cran-2020-07-04-a\u0300-16.37.33-e1756505728877-300x155.png 300w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2020\/07\/Capture-d\u2019e\u0301cran-2020-07-04-a\u0300-16.37.33-e1756505728877-768x398.png 768w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2020\/07\/Capture-d\u2019e\u0301cran-2020-07-04-a\u0300-16.37.33-e1756505728877-700x363.png 700w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2020\/07\/Capture-d\u2019e\u0301cran-2020-07-04-a\u0300-16.37.33-e1756505728877.png 1376w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-6083f0a0\" data-id=\"6083f0a0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c9822e1 elementor-widget elementor-widget-image\" data-id=\"3c9822e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"537\" src=\"https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2025\/02\/472769041_122169784418265131_5010776087486551817_n-1024x537.jpg\" class=\"attachment-large size-large wp-image-3090\" alt=\"soir\u00e9e blues avec initiation \u00e0 la danse blues\" srcset=\"https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2025\/02\/472769041_122169784418265131_5010776087486551817_n-1024x537.jpg 1024w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2025\/02\/472769041_122169784418265131_5010776087486551817_n-300x157.jpg 300w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2025\/02\/472769041_122169784418265131_5010776087486551817_n-768x402.jpg 768w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2025\/02\/472769041_122169784418265131_5010776087486551817_n-1536x805.jpg 1536w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2025\/02\/472769041_122169784418265131_5010776087486551817_n-700x367.jpg 700w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2025\/02\/472769041_122169784418265131_5010776087486551817_n.jpg 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-513e3443\" data-id=\"513e3443\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-290b0355 elementor-widget elementor-widget-image\" data-id=\"290b0355\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"507\" src=\"https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2024\/08\/Capture-de\u0301cran-2024-07-27-a\u0300-19.27.27-e1756505813621-1024x507.png\" class=\"attachment-large size-large wp-image-2490\" alt=\"Moonlight Cruise\" srcset=\"https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2024\/08\/Capture-de\u0301cran-2024-07-27-a\u0300-19.27.27-e1756505813621-1024x507.png 1024w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2024\/08\/Capture-de\u0301cran-2024-07-27-a\u0300-19.27.27-e1756505813621-300x149.png 300w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2024\/08\/Capture-de\u0301cran-2024-07-27-a\u0300-19.27.27-e1756505813621-768x380.png 768w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2024\/08\/Capture-de\u0301cran-2024-07-27-a\u0300-19.27.27-e1756505813621-1536x760.png 1536w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2024\/08\/Capture-de\u0301cran-2024-07-27-a\u0300-19.27.27-e1756505813621-2048x1014.png 2048w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2024\/08\/Capture-de\u0301cran-2024-07-27-a\u0300-19.27.27-e1756505813621-700x347.png 700w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-69a634fa\" data-id=\"69a634fa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-28740d78 elementor-widget elementor-widget-image\" data-id=\"28740d78\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"499\" src=\"https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2024\/06\/Capture-de\u0301cran-2024-05-28-a\u0300-15.18.00-e1756505872566-1024x499.png\" class=\"attachment-large size-large wp-image-2257\" alt=\"soir\u00e9e swing - initiation lindy hop\" srcset=\"https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2024\/06\/Capture-de\u0301cran-2024-05-28-a\u0300-15.18.00-e1756505872566-1024x499.png 1024w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2024\/06\/Capture-de\u0301cran-2024-05-28-a\u0300-15.18.00-e1756505872566-300x146.png 300w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2024\/06\/Capture-de\u0301cran-2024-05-28-a\u0300-15.18.00-e1756505872566-768x374.png 768w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2024\/06\/Capture-de\u0301cran-2024-05-28-a\u0300-15.18.00-e1756505872566-1536x749.png 1536w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2024\/06\/Capture-de\u0301cran-2024-05-28-a\u0300-15.18.00-e1756505872566-2048x998.png 2048w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2024\/06\/Capture-de\u0301cran-2024-05-28-a\u0300-15.18.00-e1756505872566-700x341.png 700w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-31b4b39b elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"31b4b39b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-6cb46c5e\" data-id=\"6cb46c5e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16eac67 elementor-widget elementor-widget-image\" data-id=\"16eac67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/events\/309851458353133\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"535\" src=\"https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2024\/02\/Capture-de\u0301cran-2024-02-07-a\u0300-16.03.43-e1707924209612-1024x535.png\" class=\"attachment-large size-large wp-image-2213\" alt=\"I got the blues - groov&apos;it\" srcset=\"https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2024\/02\/Capture-de\u0301cran-2024-02-07-a\u0300-16.03.43-e1707924209612-1024x535.png 1024w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2024\/02\/Capture-de\u0301cran-2024-02-07-a\u0300-16.03.43-e1707924209612-300x157.png 300w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2024\/02\/Capture-de\u0301cran-2024-02-07-a\u0300-16.03.43-e1707924209612-768x401.png 768w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2024\/02\/Capture-de\u0301cran-2024-02-07-a\u0300-16.03.43-e1707924209612-700x365.png 700w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2024\/02\/Capture-de\u0301cran-2024-02-07-a\u0300-16.03.43-e1707924209612.png 1515w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-2f8f42ca\" data-id=\"2f8f42ca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12979344 elementor-widget elementor-widget-image\" data-id=\"12979344\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/fb.me\/e\/2v6n5IfiZ\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"560\" src=\"https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2023\/12\/Capture-de\u0301cran-2023-12-12-a\u0300-23.55.46-e1756505661255-1024x560.png\" class=\"attachment-large size-large wp-image-2128\" alt=\"pratique danse blues\" srcset=\"https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2023\/12\/Capture-de\u0301cran-2023-12-12-a\u0300-23.55.46-e1756505661255-1024x560.png 1024w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2023\/12\/Capture-de\u0301cran-2023-12-12-a\u0300-23.55.46-e1756505661255-300x164.png 300w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2023\/12\/Capture-de\u0301cran-2023-12-12-a\u0300-23.55.46-e1756505661255-768x420.png 768w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2023\/12\/Capture-de\u0301cran-2023-12-12-a\u0300-23.55.46-e1756505661255-700x383.png 700w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2023\/12\/Capture-de\u0301cran-2023-12-12-a\u0300-23.55.46-e1756505661255.png 1362w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-5b6913f1\" data-id=\"5b6913f1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e73e381 elementor-widget elementor-widget-image\" data-id=\"7e73e381\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/events\/426759512753697\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"543\" src=\"https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2025\/05\/499991340_1020324436958163_4527228660710216736_n-e1748124546547-1024x543.jpg\" class=\"attachment-large size-large wp-image-3201\" alt=\"initiation blues au poisson lune\" srcset=\"https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2025\/05\/499991340_1020324436958163_4527228660710216736_n-e1748124546547-1024x543.jpg 1024w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2025\/05\/499991340_1020324436958163_4527228660710216736_n-e1748124546547-300x159.jpg 300w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2025\/05\/499991340_1020324436958163_4527228660710216736_n-e1748124546547-768x407.jpg 768w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2025\/05\/499991340_1020324436958163_4527228660710216736_n-e1748124546547-1536x815.jpg 1536w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2025\/05\/499991340_1020324436958163_4527228660710216736_n-e1748124546547-700x371.jpg 700w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2025\/05\/499991340_1020324436958163_4527228660710216736_n-e1748124546547.jpg 1602w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-db8ff59\" data-id=\"db8ff59\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b3df8f4 elementor-widget elementor-widget-image\" data-id=\"4b3df8f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"537\" src=\"https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2025\/05\/497009205_1018238593833414_1621943914482197799_n-e1748124726348-1024x537.jpg\" class=\"attachment-large size-large wp-image-3211\" alt=\"initiation blues et pratique au kiosque\" srcset=\"https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2025\/05\/497009205_1018238593833414_1621943914482197799_n-e1748124726348-1024x537.jpg 1024w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2025\/05\/497009205_1018238593833414_1621943914482197799_n-e1748124726348-300x157.jpg 300w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2025\/05\/497009205_1018238593833414_1621943914482197799_n-e1748124726348-768x402.jpg 768w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2025\/05\/497009205_1018238593833414_1621943914482197799_n-e1748124726348-1536x805.jpg 1536w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2025\/05\/497009205_1018238593833414_1621943914482197799_n-e1748124726348-2048x1073.jpg 2048w, https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2025\/05\/497009205_1018238593833414_1621943914482197799_n-e1748124726348-700x367.jpg 700w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Nos Soir\u00e9es Blues et Swing \u00e0 Montreuil et Paris Venez partager des moments inoubliables lors de nos soir\u00e9es mensuelles, soir\u00e9es exceptionnelles et soir\u00e9es estivales organis\u00e9es \u00e0 Montreuil et \u00e0 Paris. Que vous soyez danseur d\u00e9butant ou confirm\u00e9, nos \u00e9v\u00e9nements sont pens\u00e9s pour vous faire d\u00e9couvrir&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3861","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nos soir\u00e9es &amp; pratiques &#060; Groovit Dance studio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/groovit-dancestudio.com\/index.php\/nos-soirees\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nos soir\u00e9es &amp; pratiques &#060; Groovit Dance studio\" \/>\n<meta property=\"og:description\" content=\"Nos Soir\u00e9es Blues et Swing \u00e0 Montreuil et Paris Venez partager des moments inoubliables lors de nos soir\u00e9es mensuelles, soir\u00e9es exceptionnelles et soir\u00e9es estivales organis\u00e9es \u00e0 Montreuil et \u00e0 Paris. Que vous soyez danseur d\u00e9butant ou confirm\u00e9, nos \u00e9v\u00e9nements sont pens\u00e9s pour vous faire d\u00e9couvrir...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/groovit-dancestudio.com\/index.php\/nos-soirees\/\" \/>\n<meta property=\"og:site_name\" content=\"Groovit Dance studio\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dancestudiogroovit\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-18T21:36:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2025\/02\/472769041_122169784418265131_5010776087486551817_n.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/groovit-dancestudio.com\\\/index.php\\\/nos-soirees\\\/\",\"url\":\"https:\\\/\\\/groovit-dancestudio.com\\\/index.php\\\/nos-soirees\\\/\",\"name\":\"Nos soir\u00e9es &amp; pratiques &#060; Groovit Dance studio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/groovit-dancestudio.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/groovit-dancestudio.com\\\/index.php\\\/nos-soirees\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/groovit-dancestudio.com\\\/index.php\\\/nos-soirees\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/groovit-dancestudio.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/472769041_122169784418265131_5010776087486551817_n.jpg\",\"datePublished\":\"2025-08-29T22:08:06+00:00\",\"dateModified\":\"2026-02-18T21:36:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/groovit-dancestudio.com\\\/index.php\\\/nos-soirees\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/groovit-dancestudio.com\\\/index.php\\\/nos-soirees\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/groovit-dancestudio.com\\\/index.php\\\/nos-soirees\\\/#primaryimage\",\"url\":\"https:\\\/\\\/groovit-dancestudio.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/472769041_122169784418265131_5010776087486551817_n.jpg\",\"contentUrl\":\"https:\\\/\\\/groovit-dancestudio.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/472769041_122169784418265131_5010776087486551817_n.jpg\",\"width\":2000,\"height\":1048,\"caption\":\"soir\u00e9e blues avec initiation \u00e0 la danse blues\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/groovit-dancestudio.com\\\/index.php\\\/nos-soirees\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/groovit-dancestudio.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nos soir\u00e9es &amp; pratiques\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/groovit-dancestudio.com\\\/#website\",\"url\":\"https:\\\/\\\/groovit-dancestudio.com\\\/\",\"name\":\"Groovit Dance studio\",\"description\":\"Premi\u00e8re \u00e9cole de danse blues et swing \u00e0 Paris et Montreuil\",\"publisher\":{\"@id\":\"https:\\\/\\\/groovit-dancestudio.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/groovit-dancestudio.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/groovit-dancestudio.com\\\/#organization\",\"name\":\"Groov'it Dance Studio\",\"url\":\"https:\\\/\\\/groovit-dancestudio.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/groovit-dancestudio.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/groovit-dancestudio.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo_bordeaux.png\",\"contentUrl\":\"https:\\\/\\\/groovit-dancestudio.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo_bordeaux.png\",\"width\":572,\"height\":577,\"caption\":\"Groov'it Dance Studio\"},\"image\":{\"@id\":\"https:\\\/\\\/groovit-dancestudio.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dancestudiogroovit\",\"https:\\\/\\\/www.instagram.com\\\/groovit_dancestudio\\\/?hl=fr\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nos soir\u00e9es &amp; pratiques &#060; Groovit Dance studio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/groovit-dancestudio.com\/index.php\/nos-soirees\/","og_locale":"en_US","og_type":"article","og_title":"Nos soir\u00e9es &amp; pratiques &#060; Groovit Dance studio","og_description":"Nos Soir\u00e9es Blues et Swing \u00e0 Montreuil et Paris Venez partager des moments inoubliables lors de nos soir\u00e9es mensuelles, soir\u00e9es exceptionnelles et soir\u00e9es estivales organis\u00e9es \u00e0 Montreuil et \u00e0 Paris. Que vous soyez danseur d\u00e9butant ou confirm\u00e9, nos \u00e9v\u00e9nements sont pens\u00e9s pour vous faire d\u00e9couvrir...","og_url":"https:\/\/groovit-dancestudio.com\/index.php\/nos-soirees\/","og_site_name":"Groovit Dance studio","article_publisher":"https:\/\/www.facebook.com\/dancestudiogroovit","article_modified_time":"2026-02-18T21:36:03+00:00","og_image":[{"url":"https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2025\/02\/472769041_122169784418265131_5010776087486551817_n.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/groovit-dancestudio.com\/index.php\/nos-soirees\/","url":"https:\/\/groovit-dancestudio.com\/index.php\/nos-soirees\/","name":"Nos soir\u00e9es &amp; pratiques &#060; Groovit Dance studio","isPartOf":{"@id":"https:\/\/groovit-dancestudio.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/groovit-dancestudio.com\/index.php\/nos-soirees\/#primaryimage"},"image":{"@id":"https:\/\/groovit-dancestudio.com\/index.php\/nos-soirees\/#primaryimage"},"thumbnailUrl":"https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2025\/02\/472769041_122169784418265131_5010776087486551817_n.jpg","datePublished":"2025-08-29T22:08:06+00:00","dateModified":"2026-02-18T21:36:03+00:00","breadcrumb":{"@id":"https:\/\/groovit-dancestudio.com\/index.php\/nos-soirees\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/groovit-dancestudio.com\/index.php\/nos-soirees\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/groovit-dancestudio.com\/index.php\/nos-soirees\/#primaryimage","url":"https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2025\/02\/472769041_122169784418265131_5010776087486551817_n.jpg","contentUrl":"https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2025\/02\/472769041_122169784418265131_5010776087486551817_n.jpg","width":2000,"height":1048,"caption":"soir\u00e9e blues avec initiation \u00e0 la danse blues"},{"@type":"BreadcrumbList","@id":"https:\/\/groovit-dancestudio.com\/index.php\/nos-soirees\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/groovit-dancestudio.com\/"},{"@type":"ListItem","position":2,"name":"Nos soir\u00e9es &amp; pratiques"}]},{"@type":"WebSite","@id":"https:\/\/groovit-dancestudio.com\/#website","url":"https:\/\/groovit-dancestudio.com\/","name":"Groovit Dance studio","description":"Premi\u00e8re \u00e9cole de danse blues et swing \u00e0 Paris et Montreuil","publisher":{"@id":"https:\/\/groovit-dancestudio.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/groovit-dancestudio.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/groovit-dancestudio.com\/#organization","name":"Groov'it Dance Studio","url":"https:\/\/groovit-dancestudio.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/groovit-dancestudio.com\/#\/schema\/logo\/image\/","url":"https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2020\/07\/logo_bordeaux.png","contentUrl":"https:\/\/groovit-dancestudio.com\/wp-content\/uploads\/2020\/07\/logo_bordeaux.png","width":572,"height":577,"caption":"Groov'it Dance Studio"},"image":{"@id":"https:\/\/groovit-dancestudio.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dancestudiogroovit","https:\/\/www.instagram.com\/groovit_dancestudio\/?hl=fr"]}]}},"_links":{"self":[{"href":"https:\/\/groovit-dancestudio.com\/index.php\/wp-json\/wp\/v2\/pages\/3861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/groovit-dancestudio.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/groovit-dancestudio.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/groovit-dancestudio.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/groovit-dancestudio.com\/index.php\/wp-json\/wp\/v2\/comments?post=3861"}],"version-history":[{"count":0,"href":"https:\/\/groovit-dancestudio.com\/index.php\/wp-json\/wp\/v2\/pages\/3861\/revisions"}],"wp:attachment":[{"href":"https:\/\/groovit-dancestudio.com\/index.php\/wp-json\/wp\/v2\/media?parent=3861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}